{"id":3321,"date":"2023-08-20T23:00:49","date_gmt":"2023-08-20T20:00:49","guid":{"rendered":"https:\/\/terrasa-dpk.com\/?post_type=product&#038;p=3321"},"modified":"2026-06-26T17:47:33","modified_gmt":"2026-06-26T14:47:33","slug":"terasna-doshka-tardex-professional-3d-grand","status":"publish","type":"product","link":"https:\/\/terrasa-dpk.com\/uk\/product\/terasna-doshka-tardex-professional-3d-grand\/","title":{"rendered":"\u0422\u0435\u0440\u0430\u0441\u043d\u0430 \u0434\u043e\u0448\u043a\u0430 Tardex Professional 3D Grand"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"3321\" class=\"elementor elementor-3321\" data-elementor-post-type=\"product\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7560b elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7560b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-76db3fc\" data-id=\"76db3fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3a139b elementor-widget elementor-widget-heading\" data-id=\"e3a139b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u0413\u0430\u0440\u0430\u043d\u0442\u0438\u044f \u043f\u0440\u043e\u0438\u0437\u0432\u043e\u0434\u0438\u0442\u0435\u043b\u044f, \u043b\u0435\u0442:<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-32457da\" data-id=\"32457da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56c1a40 elementor-widget elementor-widget-heading\" data-id=\"56c1a40\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">25<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fcc736f\" data-id=\"fcc736f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-959fd5c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"959fd5c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c79173a\" data-id=\"c79173a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f3a4a4 elementor-widget elementor-widget-text-editor\" data-id=\"0f3a4a4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0422\u0435\u0440\u0430\u0441\u043d\u0430 \u0434\u043e\u0448\u043a\u0430 Tardex Professional 3D Grand \u2013 \u0446\u0435 \u0447\u0443\u0434\u043e\u0432\u0438\u0439 \u0432\u0438\u0431\u0456\u0440, \u0449\u043e\u0431 \u0441\u0442\u0432\u043e\u0440\u0438\u0442\u0438 \u0434\u043e\u0432\u0433\u043e\u0432\u0456\u0447\u043d\u0438\u0439 \u0442\u0430 \u043a\u0440\u0430\u0441\u0438\u0432\u0438\u0439 \u0434\u0438\u0437\u0430\u0439\u043d \u043f\u0456\u0434\u043b\u043e\u0433, \u043f\u043e\u0434\u0456\u0443\u043c\u0456\u0432, \u043f\u043e\u043c\u043e\u0441\u0442\u0456\u0432 \u043d\u0430 \u0442\u0435\u0440\u0430\u0441\u0430\u0445, \u0431\u0456\u043b\u044f \u0431\u0430\u0441\u0435\u0439\u043d\u0456\u0432. \u0412\u043e\u043d\u0430 \u043f\u043e\u0454\u0434\u043d\u0443\u0454 \u0443 \u0441\u043e\u0431\u0456 \u043f\u0440\u0438\u0432\u0430\u0431\u043b\u0438\u0432\u0456\u0441\u0442\u044c \u0456 \u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456\u0441\u0442\u044c, \u0432\u043e\u043d\u0430 \u0441\u043b\u0443\u0436\u0438\u0442\u0438\u043c\u0435 \u0434\u043e\u0432\u0433\u0456 \u0440\u043e\u043a\u0438 \u0431\u0435\u0437 \u0441\u043b\u0456\u0434\u0456\u0432 \u0437\u043d\u043e\u0441\u0443.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-468525c elementor-widget elementor-widget-text-editor\" data-id=\"468525c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0422\u0435\u0440\u0430\u0441\u043d\u0430 \u0434\u043e\u0448\u043a\u0430 Tardex Professional 3D Grand \u2013 \u0454 \u044f\u043a\u0456\u0441\u043d\u0438\u043c, \u0441\u0435\u0440\u0442\u0438\u0444\u0456\u043a\u043e\u0432\u0430\u043d\u0438\u043c \u0442\u043e\u0432\u0430\u0440\u043e\u043c \u0432 \u0423\u043a\u0440\u0430\u0457\u043d\u0456.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a98777 elementor-widget elementor-widget-text-editor\" data-id=\"7a98777\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0412\u0441\u0456 \u0442\u043e\u0432\u0430\u0440\u0438 \u0432 \u043c\u0430\u0433\u0430\u0437\u0438\u043d\u0456 Terrasa-DPK\u00ae &#8211; \u0446\u0435 \u0442\u0456\u043b\u044c\u043a\u0438 \u043f\u0435\u0440\u0448\u043e\u043a\u043b\u0430\u0441\u043d\u0456, \u0435\u043a\u043e\u043b\u043e\u0433\u0456\u0447\u043d\u0456 \u0442\u0430 \u0430\u0431\u0441\u043e\u043b\u044e\u0442\u043d\u043e \u0431\u0435\u0437\u043f\u0435\u0447\u043d\u0456 \u0434\u043b\u044f \u0437\u0434\u043e\u0440\u043e\u0432&#8217;\u044f \u0432\u0438\u0440\u043e\u0431\u0438, \u0443 \u0442\u043e\u043c\u0443 \u0447\u0438\u0441\u043b\u0456 \u0422\u0435\u0440\u0430\u0441\u043d\u0430 \u0434\u043e\u0448\u043a\u0430 Tardex Professional 3D Grand. \u041c\u0438 \u0434\u0431\u0430\u0454\u043c\u043e \u043f\u0440\u043e \u0432\u0441\u0456 \u0431\u0430\u0436\u0430\u043d\u043d\u044f \u0441\u0432\u043e\u0457\u0445 \u043f\u043e\u043a\u0443\u043f\u0446\u0456\u0432: \u044f\u043a\u0456\u0441\u0442\u044c, \u043d\u0430\u0434\u0456\u0439\u043d\u0456\u0441\u0442\u044c, \u0434\u0438\u0437\u0430\u0439\u043d, \u0434\u043e\u0441\u0442\u0443\u043f\u043d\u0430 \u0446\u0456\u043d\u043e\u0432\u0430 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0430.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abb3911 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"abb3911\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0427\u043e\u043c\u0443 \u0432\u0438\u0431\u0438\u0440\u0430\u044e\u0442\u044c \u043d\u0430\u0448 \u043c\u0430\u0433\u0430\u0437\u0438\u043d?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u043f\u0440\u043e\u0444\u0435\u0441\u0456\u0439\u043d\u0456 \u043a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u0446\u0456\u0457,<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u043f\u043e\u0441\u0442\u0430\u0432\u043a\u0430 \u043f\u043e \u041a\u0438\u0454\u0432\u0443 \u043f\u0440\u043e\u0442\u044f\u0433\u043e\u043c \u0434\u043d\u044f, \u043f\u043e \u0423\u043a\u0440\u0430\u0457\u043d\u0456 2-3 \u0434\u043d\u0456,<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u043f\u0440\u044f\u043c\u0456 \u043f\u043e\u0441\u0442\u0430\u0432\u043a\u0438 \u0437\u0456 \u0441\u043a\u043b\u0430\u0434\u0456\u0432 \u0432\u0438\u0440\u043e\u0431\u043d\u0438\u043a\u0456\u0432,<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0442\u0456\u043b\u044c\u043a\u0438 \u044f\u043a\u0456\u0441\u043d\u0456 \u0442\u0435\u0440\u0430\u0441\u043d\u0456 \u0434\u043e\u0448\u043a\u0438 \u0456\u0437 \u0441\u0435\u0440\u0442\u0438\u0444\u0456\u043a\u0430\u0446\u0456\u0454\u044e,<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u043e\u043f\u0442\u043e\u0432\u0456 \u0437\u043d\u0438\u0436\u043a\u0438 \u043d\u0430 \u0422\u0435\u0440\u0430\u0441\u043d\u0430 \u0434\u043e\u0448\u043a\u0430 Tardex Professional 3D Grand - \u0434\u043b\u044f \u0432\u0435\u043b\u0438\u043a\u0438\u0445 \u0437\u0430\u043c\u043e\u0432\u043b\u0435\u043d\u044c,<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0441\u0432\u043e\u044f \u0431\u0440\u0438\u0433\u0430\u0434\u0430 \u043c\u0430\u0439\u0441\u0442\u0440\u0456\u0432.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2c35e9 elementor-widget elementor-widget-text-editor\" data-id=\"e2c35e9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0406\u043d\u0442\u0435\u0440\u043d\u0435\u0442-\u043c\u0430\u0433\u0430\u0437\u0438\u043d Terrasa-DPK\u00ae \u0454 \u043e\u0444\u0456\u0446\u0456\u0439\u043d\u0438\u043c \u043f\u0440\u043e\u0434\u0430\u0432\u0446\u0435\u043c \u043d\u0430\u0439\u043a\u0440\u0430\u0449\u0438\u0445 \u0432\u0438\u0440\u043e\u0431\u043d\u0438\u043a\u0456\u0432 Tardex, Woodlux, ARS, HOLZDORF \u043d\u0430 \u0442\u0435\u0440\u0438\u0442\u043e\u0440\u0456\u0457 \u0423\u043a\u0440\u0430\u0457\u043d\u0438. \u0422\u0435\u0440\u0430\u0441\u043d\u0430 \u0434\u043e\u0448\u043a\u0430 Tardex Professional 3D Grand \u043f\u043e\u0441\u0442\u0430\u0432\u043b\u044f\u0454\u0442\u044c\u0441\u044f \u0431\u0435\u0437\u043f\u043e\u0441\u0435\u0440\u0435\u0434\u043d\u044c\u043e \u0437 \u0432\u0438\u0440\u043e\u0431\u043d\u0438\u0446\u0442\u0432\u0430.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ffc14f elementor-widget elementor-widget-text-editor\" data-id=\"0ffc14f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0417\u0432\u0435\u0440\u043d\u0456\u0442\u044c \u0443\u0432\u0430\u0433\u0443, \u0449\u043e \u0432\u0456\u0434\u0442\u0456\u043d\u043e\u043a \u0442\u043e\u0432\u0430\u0440\u0443: \u0422\u0435\u0440\u0430\u0441\u043d\u0430 \u0434\u043e\u0448\u043a\u0430 Tardex Professional 3D Grand \u043d\u0430 \u0444\u043e\u0442\u043e\u0433\u0440\u0430\u0444\u0456\u0457 \u043c\u043e\u0436\u0435 \u0442\u0440\u043e\u0445\u0438 \u0432\u0456\u0434\u0440\u0456\u0437\u043d\u044f\u0442\u0438\u0441\u044c \u0432\u0456\u0434 \u0440\u0435\u0430\u043b\u044c\u043d\u043e\u0433\u043e \u0437\u0430 \u0440\u0430\u0445\u0443\u043d\u043e\u043a \u043d\u0430\u043b\u0430\u0448\u0442\u0443\u0432\u0430\u043d\u044c \u0435\u043a\u0440\u0430\u043d\u0430.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90dc7d8 elementor-widget elementor-widget-text-editor\" data-id=\"90dc7d8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0414\u043e\u0441\u0442\u0430\u0432\u043b\u044f\u0454\u0442\u044c\u0441\u044f \u0422\u0435\u0440\u0430\u0441\u043d\u0430 \u0434\u043e\u0448\u043a\u0430 Tardex Professional 3D Grand \u043f\u043e \u0432\u0441\u0456\u0439 \u0423\u043a\u0440\u0430\u0457\u043d\u0456 (\u041a\u0438\u0457\u0432, \u0427\u0435\u0440\u043a\u0430\u0441\u0438, \u0414\u043d\u0456\u043f\u0440\u043e, \u0416\u0438\u0442\u043e\u043c\u0438\u0440, \u041f\u043e\u043b\u0442\u0430\u0432\u0430, \u041e\u0434\u0435\u0441\u0430, \u0425\u0430\u0440\u043a\u0456\u0432, \u041b\u044c\u0432\u0456\u0432, \u0427\u0435\u0440\u043d\u0456\u0433\u0456\u0432, \u0412\u0456\u043d\u043d\u0438\u0446\u044f, \u041c\u0430\u0440\u0456\u0443\u043f\u043e\u043b\u044c, \u0423\u0436\u0433\u043e\u0440\u043e\u0434, \u041c\u0438\u043a\u043e\u043b\u0430\u0457\u0432, \u0425\u043c\u0435\u043b\u044c\u043d\u0438\u0446\u044c\u043a\u0438\u0439, \u041a\u0440\u0438\u0432\u0438\u0439 \u0420\u0456\u0433, \u0417\u0430\u043f\u043e\u0440\u0456\u0436\u0436\u044f, \u0427\u0435\u0440\u043d\u0456\u0432\u0446\u0456, \u0421\u0443\u043c\u0438, \u0420\u0435\u043d\u0456, \u0406\u0437\u043c\u0430\u0457\u043b, \u0420\u0456\u0432\u043d\u0435, \u0425\u0435\u0440\u0441\u043e\u043d \u0442\u0430 \u0456\u043d\u0448\u0456 .)\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0422\u0435\u0440\u0430\u0441\u043d\u0430 \u0434\u043e\u0448\u043a\u0430 Tardex Professional 3D Grand \u043d\u0435 \u043c\u0430\u0454 \u0443 \u0441\u0432\u043e\u0457\u0439 \u0441\u0442\u0440\u0443\u043a\u0442\u0443\u0440\u0456 \u043f\u043e\u0440\u043e\u0436\u043d\u0438\u043d, \u0449\u043e \u0434\u043e\u0437\u0432\u043e\u043b\u044f\u0454 \u0457\u0439 \u0432\u0438\u0442\u0440\u0438\u043c\u0443\u0432\u0430\u0442\u0438 \u0432\u0435\u043b\u0438\u0447\u0435\u0437\u043d\u0435 \u043d\u0430\u0432\u0430\u043d\u0442\u0430\u0436\u0435\u043d\u043d\u044f \u0434\u043e 2000 \u043a\u0433\/\u043c2! \u0414\u043e\u0434\u0430\u0439\u0442\u0435 \u0434\u043e \u0446\u044c\u043e\u0433\u043e \u043f\u0440\u0438\u0454\u043c\u043d\u0435 \u0441\u043f\u0456\u0432\u0432\u0456\u0434\u043d\u043e\u0448\u0435\u043d\u043d\u044f \u0446\u0456\u043d\u0438 \u0442\u0430 \u044f\u043a\u043e\u0441\u0442\u0456, \u0434\u0432\u043e\u0441\u0442\u043e\u0440\u043e\u043d\u043d\u0456\u0439 \u0440\u0435\u043b\u044c\u0454\u0444 \u0442\u0430 \u043f\u0440\u0438\u0432\u0430\u0431\u043b\u0438\u0432\u0438\u0439 \u0437\u043e\u0432\u043d\u0456\u0448\u043d\u0456\u0439 \u0432\u0438\u0433\u043b\u044f\u0434.<\/p>\n<p>\u0422\u0435\u0440\u0430\u0441\u043d\u0430 \u0434\u043e\u0448\u043a\u0430 Tardex Professional 3D Grand \u0456\u0434\u0435\u0430\u043b\u044c\u043d\u043e \u043f\u0456\u0434\u0456\u0439\u0434\u0435 \u0434\u043b\u044f \u0432\u0435\u043b\u0438\u043a\u0438\u0445 \u0434\u043e\u043c\u0430\u0448\u043d\u0456\u0445 \u0442\u0435\u0440\u0430\u0441, \u044f\u043a \u043f\u0456\u0434\u043b\u043e\u0433\u043e\u0432\u0435 \u043f\u043e\u043a\u0440\u0438\u0442\u0442\u044f \u0434\u043b\u044f \u044f\u0445\u0442, \u0430 \u0442\u0430\u043a\u043e\u0436 \u0434\u043b\u044f \u043a\u043e\u043c\u0435\u0440\u0446\u0456\u0439\u043d\u043e\u0433\u043e \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u0430\u043d\u043d\u044f. \u042f\u043a\u0449\u043e \u0445\u043e\u0447\u0435\u0442\u0435 \u043c\u0456\u0446\u043d\u0443 \u0442\u0435\u0440\u0430\u0441\u0443 \u0434\u043b\u044f \u043a\u0430\u0444\u0435 \u0447\u0438 \u0440\u0435\u0441\u0442\u043e\u0440\u0430\u043d\u0443, \u0432 \u044f\u043a\u043e\u043c\u0443 \u043e\u0447\u0456\u043a\u0443\u0454\u0442\u044c\u0441\u044f \u0432\u0435\u043b\u0438\u0447\u0435\u0437\u043d\u0438\u0439 \u043f\u043e\u0442\u0456\u043a \u0432\u0456\u0434\u0432\u0456\u0434\u0443\u0432\u0430\u0447\u0456\u0432 \u2014 Tardex Professional \u0441\u0430\u043c\u0435 \u0442\u0430 \u0434\u043e\u0448\u043a\u0430, \u0437 \u044f\u043a\u043e\u0457 \u043f\u043e\u0442\u0440\u0456\u0431\u043d\u043e \u0431\u0443\u0434\u0443\u0432\u0430\u0442\u0438 \u0442\u0430\u043a\u0443 \u0442\u0435\u0440\u0430\u0441\u0443.<\/p>\n<p><span style=\"font-size: 21px; color: #cd5025;\">\u0426\u0456\u043d\u0430 \u043f\u0440\u043e\u0434\u0443\u043a\u0446\u0456\u0457 \u043f\u0440\u0435\u0434\u0441\u0442\u0430\u0432\u043b\u0435\u043d\u0430 \u0437\u0430 \u043c\u00b2.<\/span><\/p>\n","protected":false},"featured_media":2960,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[292,295,296,298,294],"product_tag":[],"class_list":{"0":"post-3321","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tardex-uk","7":"product_cat-gladka-doshka","8":"product_cat-monolitna-doshka","9":"product_cat-ryflena-doshka","10":"product_cat-terasna-doshka","12":"first","13":"instock","14":"sale","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/terrasa-dpk.com\/uk\/wp-json\/wp\/v2\/product\/3321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/terrasa-dpk.com\/uk\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/terrasa-dpk.com\/uk\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/terrasa-dpk.com\/uk\/wp-json\/wp\/v2\/comments?post=3321"}],"version-history":[{"count":6,"href":"https:\/\/terrasa-dpk.com\/uk\/wp-json\/wp\/v2\/product\/3321\/revisions"}],"predecessor-version":[{"id":3635,"href":"https:\/\/terrasa-dpk.com\/uk\/wp-json\/wp\/v2\/product\/3321\/revisions\/3635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/terrasa-dpk.com\/uk\/wp-json\/wp\/v2\/media\/2960"}],"wp:attachment":[{"href":"https:\/\/terrasa-dpk.com\/uk\/wp-json\/wp\/v2\/media?parent=3321"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/terrasa-dpk.com\/uk\/wp-json\/wp\/v2\/product_brand?post=3321"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/terrasa-dpk.com\/uk\/wp-json\/wp\/v2\/product_cat?post=3321"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/terrasa-dpk.com\/uk\/wp-json\/wp\/v2\/product_tag?post=3321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}